{"id":16236,"date":"2024-08-31T19:31:51","date_gmt":"2024-08-31T22:31:51","guid":{"rendered":"https:\/\/fm22.com.ar\/?p=16236"},"modified":"2024-08-31T19:52:05","modified_gmt":"2024-08-31T22:52:05","slug":"la-obra-en-el-san-bernardo-avanza-en-diferentes-frentes-para-su-ampliacion-y-refuncionalizacion","status":"publish","type":"post","link":"https:\/\/fm22.com.ar\/index.php\/2024\/08\/31\/la-obra-en-el-san-bernardo-avanza-en-diferentes-frentes-para-su-ampliacion-y-refuncionalizacion\/","title":{"rendered":"La obra en el San Bernardo avanza en diferentes frentes para su ampliaci\u00f3n y refuncionalizaci\u00f3n"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Los trabajos se ejecutan en el edificio para la administraci\u00f3n y la central de esterilizaci\u00f3n y se proyecta la construcci\u00f3n del bloque cr\u00edtico. Los ministros Mangione, Camacho y Dib Ashur recorrieron la obra.<\/p>\n<p>La obra de ampliaci\u00f3n y refuncionalizaci\u00f3n del hospital San Bernardo avanza en diferentes frentes. Mientras los obreros trabajan en la construcci\u00f3n del edificio donde funcionar\u00e1 la Administraci\u00f3n y la central de esterilizaci\u00f3n, se organizan los trabajos para levantar el bloque cr\u00edtico que albergar\u00e1 quir\u00f3fanos, boxes para terapia intensiva y unidad coronaria, y camas para unidad del quemado, terapia intermedia, recuperaci\u00f3n cirug\u00eda mayor y recuperaci\u00f3n de cirug\u00eda ambulatoria.<\/p>\n<p>Los ministros de Infraestructura, <strong>Sergio Camacho<\/strong>; <strong>Salud P\u00fablica<\/strong>, <strong>Federico Mangione<\/strong>; y de Econom\u00eda y Servicios P\u00fablicos, <strong>Roberto Dib Ashur<\/strong>; recorrieron la obra junto al gerente, <strong>Pablo Salom\u00f3n<\/strong>, y profesionales del San Bernardo. Los t\u00e9cnicos a cargo del seguimiento de la obra los pusieron al d\u00eda sobre los trabajos realizados y los que est\u00e1n en marcha, adem\u00e1s de los plazos de ejecuci\u00f3n.<\/p>\n<p>El plan de trabajo es complejo ya que ninguna de las \u00e1reas dej\u00f3 de funcionar y los movimientos internos son varios. Con inversi\u00f3n del Fonplata y del Gobierno de la Provincia, el nosocomio sumar\u00e1 confort para pacientes y profesionales y tecnolog\u00eda para las prestaciones: \u201cEsta es una obra que hac\u00eda falta, sobre todo despu\u00e9s de 64 a\u00f1os que tiene el hospital. Se cerrar\u00e1 el c\u00edrculo de excelencia\u201d, asegur\u00f3 Salom\u00f3n, quien reiter\u00f3 su agradecimiento al gobernador <strong>Gustavo S\u00e1enz.<\/strong><\/p>\n<div class=\"col-md-8 col-12 mb-4\">\n<p>El hospital San Bernardo es de referencia en Salta, la regi\u00f3n e incluso en pa\u00edses lim\u00edtrofes. Es reconocido por la calidad de sus servicios, por lo que las renovaciones fueron bienvenidas por la comunidad. Para mantener su performance se proyect\u00f3 esta obra de envergadura que abarcar\u00e1 m\u00e1s de 11.000 metros cuadrados y contempla la construcci\u00f3n de esas tres \u00e1reas preponderantes: administraci\u00f3n, esterilizaci\u00f3n y bloque cr\u00edtico.<\/p>\n<p>La secretaria de Financiamiento y Planificaci\u00f3n Financiera, <strong>Liliana Corona<\/strong>, inform\u00f3 que en breve se lanzar\u00e1 la licitaci\u00f3n para la compra del mobiliario. \u201cSe ha trabajado siempre todo con un plan de contingencia, construyendo, derribando y habilitando paulatinamente etapas para no interponer la obra al funcionamiento de este hospital\u201d, dijo.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Los trabajos se ejecutan en el edificio para la administraci\u00f3n y la central de esterilizaci\u00f3n y se proyecta la construcci\u00f3n del bloque cr\u00edtico. Los ministros Mangione, Camacho y Dib Ashur recorrieron la obra. La obra de ampliaci\u00f3n y refuncionalizaci\u00f3n del hospital San Bernardo avanza en diferentes frentes. Mientras los obreros trabajan en la construcci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":16237,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/16236"}],"collection":[{"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=16236"}],"version-history":[{"count":1,"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/16236\/revisions"}],"predecessor-version":[{"id":16238,"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/16236\/revisions\/16238"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/media\/16237"}],"wp:attachment":[{"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=16236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=16236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=16236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}