{"id":12187,"date":"2023-05-04T17:07:48","date_gmt":"2023-05-04T20:07:48","guid":{"rendered":"https:\/\/fm22.com.ar\/?p=12187"},"modified":"2023-05-04T17:07:48","modified_gmt":"2023-05-04T20:07:48","slug":"es-ley-la-capacitacion-obligatoria-en-maniobra-de-heimlich-en-las-escuelas","status":"publish","type":"post","link":"https:\/\/fm22.com.ar\/index.php\/2023\/05\/04\/es-ley-la-capacitacion-obligatoria-en-maniobra-de-heimlich-en-las-escuelas\/","title":{"rendered":"Es Ley la capacitaci\u00f3n obligatoria en maniobra de Heimlich en las Escuelas"},"content":{"rendered":"<div class=\"container w-75\">\n<p>&nbsp;<\/p>\n<p>El proyecto sancionado de forma definitiva establece que se deber\u00e1 realizar la capacitaci\u00f3n obligatoria de la maniobra de Heimlich en todos los establecimientos educativos p\u00fablicos y de gesti\u00f3n privada en la provincia.<\/p>\n<p>Cabe destacar que dicha maniobra consiste en una t\u00e9cnica de comprensi\u00f3n abdominal utilizada como procedimiento de primeros auxilios para desobstruir el conducto respiratorio, bloqueado por un trozo de alimento o cualquier otro objeto.<\/p>\n<p>La autoridad de aplicaci\u00f3n deber\u00e1 realizar campa\u00f1as de difusi\u00f3n masiva sobre la importancia de la Maniobra de Heimlich y el modo correcto de efectuarla; y, determinar el contenido y modalidad de las capacitaciones, seg\u00fan el \u00e1mbito en el que se brinden.<\/p>\n<p>La iniciativa aprobada en la \u00faltima reuni\u00f3n del Senado, hab\u00eda obtenido la media sanci\u00f3n por unanimidad durante la segunda sesi\u00f3n ordinaria de la C\u00e1mara de Diputados, el 14 de marzo pasado.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; El proyecto sancionado de forma definitiva establece que se deber\u00e1 realizar la capacitaci\u00f3n obligatoria de la maniobra de Heimlich en todos los establecimientos educativos p\u00fablicos y de gesti\u00f3n privada en la provincia. Cabe destacar que dicha maniobra consiste en una t\u00e9cnica de comprensi\u00f3n abdominal utilizada como procedimiento de primeros auxilios para desobstruir el conducto [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":12188,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[],"_links":{"self":[{"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/12187"}],"collection":[{"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=12187"}],"version-history":[{"count":1,"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/12187\/revisions"}],"predecessor-version":[{"id":12189,"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/12187\/revisions\/12189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/media\/12188"}],"wp:attachment":[{"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=12187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=12187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=12187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}