{"id":10369,"date":"2023-01-21T16:09:40","date_gmt":"2023-01-21T19:09:40","guid":{"rendered":"https:\/\/fm22.com.ar\/?p=10369"},"modified":"2023-01-21T16:10:49","modified_gmt":"2023-01-21T19:10:49","slug":"se-instruira-un-sumario-administrativo-por-el-incidente-en-el-hospital-papa-francisco","status":"publish","type":"post","link":"https:\/\/fm22.com.ar\/index.php\/2023\/01\/21\/se-instruira-un-sumario-administrativo-por-el-incidente-en-el-hospital-papa-francisco\/","title":{"rendered":"Se instruir\u00e1 un sumario administrativo por el incidente en el hospital Papa Francisco"},"content":{"rendered":"<p>Luego de haber vivido una noche de terror en el Hospital Papa Francisco cuando un hombre se acerc\u00f3 a pedir por favor que llamen a una ambulancia para su esposa embarazada que se encontraba en trabajo de parto, no quisieron atenderla, rompi\u00f3 bolsa y su beb\u00e9 cay\u00f3 al suelo en las afueras del Hospital Papa Francisco.<\/p>\n<p>El hecho sucedi\u00f3 cerca de las 22:00 horas relat\u00f3 el esposo de la mujer &#8220;a mi mujer le dol\u00eda mucho el est\u00f3mago, llegamos en moto y avis\u00e9 que est\u00e1bamos yendo para que nos atiendan, pero una mujer que forma parte del personal del hospital dijo que no hab\u00eda personal&#8221;.<\/p>\n<p>&#8220;Mi mujer me dijo que le temblaban las piernas, no aguantaba m\u00e1s y rompi\u00f3 bolsa, fue en ese preciso momento cuando sent\u00ed algo en mis piernas, mir\u00e9 y era la beb\u00e9 que hab\u00eda ca\u00eddo.<\/p>\n<p><strong>Investigaci\u00f3n para tomar medidas correctivas<\/strong><\/p>\n<p>El ministro de Salud P\u00fablica dispuso la medida, a fin de dilucidar las responsabilidades de las personas involucradas y tomar las medidas correctivas que sean necesarias.<\/p>\n<p>El ministro de Salud P\u00fablica, Federico Mangione, dispuso la instrucci\u00f3n de un sumario administrativo a fin de dilucidar los hechos acaecidos en el hospital Papa Francisco y tomar las medidas pertinentes.<\/p>\n<p>Al respecto, expres\u00f3 que se har\u00e1 una investigaci\u00f3n minuciosa, \u201cpara tomar las medidas correctivas necesarias, a fin de que hechos similares no vuelvan a producirse\u201d.<\/p>\n<p>Sobre el incidente, Mangione dijo que \u201cla se\u00f1ora no recibi\u00f3 ayuda, se le neg\u00f3 atenci\u00f3n, por eso vamos a investigar el hecho y tomar las medidas que correspondan\u201d.<\/p>\n<p>Tambi\u00e9n explic\u00f3 el hecho de que en el hospital Papa Francisco no hubiera profesionales para asistir un parto. \u201cEn este momento, el hospital no tiene ginec\u00f3logo ni obstetra, porque como es sabido, fue acondicionado para trabajar espec\u00edficamente con pacientes COVID, pero todo m\u00e9dico est\u00e1 preparado para recibir un nacimiento. Lo que pas\u00f3 es que la persona que atendi\u00f3 a la paciente no comunic\u00f3 lo que estaba sucediendo\u201d.<\/p>\n<p>Adem\u00e1s aclar\u00f3 que, tanto la madre como la hija reci\u00e9n nacida, fueron trasladadas al hospital Materno Infantil en ambulancia del hospital Papa Francisco.<\/p>\n<p>Con respecto al estado de la salud de la madre y la beb\u00e9, el Ministro dijo que \u201cla se\u00f1ora est\u00e1 bien, estable, con control m\u00e9dico; la beb\u00e9 sufri\u00f3 una fractura de clav\u00edcula, tiene traumatismo encefalocraneano, se hicieron estudios minuciosos y est\u00e1 fuera de peligro, bajo control m\u00e9dico\u201d.<\/p>\n<p>Tambi\u00e9n dijo que \u201cconstantemente estoy llamando, para cerciorarme de que no les pase nada\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego de haber vivido una noche de terror en el Hospital Papa Francisco cuando un hombre se acerc\u00f3 a pedir por favor que llamen a una ambulancia para su esposa embarazada que se encontraba en trabajo de parto, no quisieron atenderla, rompi\u00f3 bolsa y su beb\u00e9 cay\u00f3 al suelo en las afueras del Hospital Papa [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10370,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10369"}],"collection":[{"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=10369"}],"version-history":[{"count":2,"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10369\/revisions"}],"predecessor-version":[{"id":10372,"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10369\/revisions\/10372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/media\/10370"}],"wp:attachment":[{"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=10369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=10369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fm22.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=10369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}